{"id":4009,"date":"2024-11-03T13:22:00","date_gmt":"2024-11-03T12:22:00","guid":{"rendered":"https:\/\/www.vivakirche-liestal.ch\/?post_type=wpfc_sermon&#038;p=4009"},"modified":"2024-11-03T13:22:03","modified_gmt":"2024-11-03T12:22:03","slug":"vom-zweifel-zum-glauben","status":"publish","type":"wpfc_sermon","link":"https:\/\/www.vivakirche-liestal.ch\/en\/predigten\/vom-zweifel-zum-glauben\/","title":{"rendered":"From doubt to faith"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":10,"featured_media":4006,"comment_status":"closed","ping_status":"closed","template":"","wpfc_preacher":[37],"wpfc_sermon_series":[206],"wpfc_sermon_topics":[118,205],"wpfc_bible_book":[],"wpfc_service_type":[12],"class_list":{"0":"wpfc_preacher-markus-burkhart","1":"wpfc_sermon_series-glaube-auf-dem-pruefstand","2":"wpfc_sermon_topics-glaube","3":"wpfc_sermon_topics-zweifel","4":"wpfc-sermon-single","5":"post-4009","6":"wpfc_sermon","7":"type-wpfc_sermon","8":"status-publish","9":"has-post-thumbnail","10":"hentry","15":"wpfc_service_type-gottesdienst"},"acf":[],"sermons_blog_filters_topics":"\t\t\t\t<div class=\"sm-filtering\">\n\t\t\t\t\t<div id=\"wpfc_sermon_sorting\" class=\"no-spacing\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"sortTopics\" style=\"display: inline-block\">\n\t\t\t\t<form action=\"https:\/\/www.vivakirche-liestal.ch\/en\/wp-json\/wp\/v2\/wpfc_sermon\/4009\/\" method=\"get\">\n\t\t\t\t\t<select name=\"wpfc_sermon_topics\"\n\t\t\t\t\t\t\ttitle=\"Topic\"\n\t\t\t\t\t\t\tid=\"wpfc_sermon_topics\"\n\t\t\t\t\t\t\tonchange=\"if(this.options[this.selectedIndex].value !== ''){return this.form.submit()}else{window.location = window.location.href.split('?')[0];}\"\n\t\t\t\t\t\t\tautocomplete=\"off\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t<option value=\"\">Topic<\/option>\n\t\t\t\t\t\t<option value=\"abendmahl\" >Abendmahl<\/option><option value=\"advent\" >Advent<\/option><option value=\"alltag\" >Alltag<\/option><option value=\"auferstehung\" >Auferstehung<\/option><option value=\"barmherzigkeit\" >Barmherzigkeit<\/option><option value=\"begegnung\" >Begegnung<\/option><option value=\"berufung\" >Berufung<\/option><option value=\"bettag\" >Bettag<\/option><option value=\"beurteilung\" >Beurteilung<\/option><option value=\"beziehung\" >Beziehung<\/option><option value=\"beziehung-zu-jesus-christus\" >Beziehung zu Jesus Christus<\/option><option value=\"brot-des-lebens\" >Brot des Lebens<\/option><option value=\"busse\" >Busse<\/option><option value=\"corrie-ten-boom\" >Corrie ten Boom<\/option><option value=\"dank\" >Dank<\/option><option value=\"dankbarkeit\" >Dankbarkeit<\/option><option value=\"das-geschenk-der-erloesung\" >Das Geschenk der Erl\u00f6sung<\/option><option value=\"demut\" >Demut<\/option><option value=\"der-gute-hirte\" >Der gute Hirte<\/option><option value=\"dienen\" >Dienen<\/option><option value=\"disziplin\" >Disziplin<\/option><option value=\"durch-erholsames-gebet\" >durch erholsames Gebet<\/option><option value=\"elisabeth-elliott\" >Elisabeth Elliott<\/option><option value=\"erfuellung\" >Erf\u00fcllung<\/option><option value=\"erntedank\" >Erntedank<\/option><option value=\"erwartungen\" >Erwartungen<\/option><option value=\"ewigkeit\" >Ewigkeit<\/option><option value=\"feier\" >Feier<\/option><option value=\"feiertage\" >Feiertage<\/option><option value=\"feste\" >Feste<\/option><option value=\"freude\" >Freude<\/option><option value=\"friede\" >Friede<\/option><option value=\"frucht\" >Frucht<\/option><option value=\"fuerbitte\" >F\u00fcrbitte<\/option><option value=\"gebet\" >Gebet<\/option><option value=\"geistlicher-blick\" >Geistlicher Blick<\/option><option value=\"geistliches-leben\" >geistliches Leben<\/option><option value=\"gemeinde\" >Gemeinde<\/option><option value=\"gemeinschaft\" >Gemeinschaft<\/option><option value=\"gericht\" >Gericht<\/option><option value=\"glaube\" >Glaube<\/option><option value=\"glueck\" >Gl\u00fcck<\/option><option value=\"gnade\" >Gnade<\/option><option value=\"gnadengaben\" >Gnadengaben<\/option><option value=\"golgatha\" >Golgatha<\/option><option value=\"gottes-angesicht\" >Gottes Angesicht<\/option><option value=\"gottes-gebot\" >Gottes Gebot<\/option><option value=\"gottes-gegenwart\" >Gottes Gegenwart<\/option><option value=\"gottes-heiligkeit\" >Gottes Heiligkeit<\/option><option value=\"gottes-realitaet\" >Gottes Realit\u00e4t<\/option><option value=\"gottes-stimme\" >Gottes Stimme<\/option><option value=\"gottes-wort\" >Gottes Wort<\/option><option value=\"gottes-bild\" >Gottes-Bild<\/option><option value=\"goettliche-dimension\" >G\u00f6ttliche Dimension<\/option><option value=\"gut-und-boese\" >Gut und B\u00f6se<\/option><option value=\"heiligtum\" >Heiligtum<\/option><option value=\"herausgefordert\" >herausgefordert<\/option><option value=\"hoffnung\" >Hoffnung<\/option><option value=\"horizonterweiterung\" >Horizonterweiterung<\/option><option value=\"jabez\" >Jabez<\/option><option value=\"jahreslosung\" >Jahreslosung<\/option><option value=\"jesus-christus\" >Jesus Christus<\/option><option value=\"jesus-christus-als-herr\" >Jesus Christus als Herr<\/option><option value=\"jesus-christus-als-retter\" >Jesus Christus als Retter<\/option><option value=\"karfreitag\" >Karfreitag<\/option><option value=\"katastrophen\" >Katastrophen<\/option><option value=\"knecht-oder-kind-gottes\" >Knecht oder Kind Gottes<\/option><option value=\"kreuz\" >Kreuz<\/option><option value=\"kriege\" >Kriege<\/option><option value=\"krisen\" >Krisen<\/option><option value=\"lauheit\" >Lauheit<\/option><option value=\"leben\" >Leben<\/option><option value=\"lebenssinn\" >Lebenssinn<\/option><option value=\"lebensziel\" >Lebensziel<\/option><option value=\"leiden-als-mutter\" >Leiden als Mutter<\/option><option value=\"licht\" >Licht<\/option><option value=\"liebe\" >Liebe<\/option><option value=\"luege\" >L\u00fcge<\/option><option value=\"messias\" >Messias<\/option><option value=\"mutter-glueck\" >Mutter-Gl\u00fcck<\/option><option value=\"mutter-sein\" >Mutter-Sein<\/option><option value=\"nachfolge\" >Nachfolge<\/option><option value=\"neu\" >Neu<\/option><option value=\"neu-schoepfung\" >Neu-Sch\u00f6pfung<\/option><option value=\"neue-wirklichkeit\" >Neue Wirklichkeit<\/option><option value=\"neues-leben\" >Neues Leben<\/option><option value=\"opfer\" >Opfer<\/option><option value=\"ostern\" >Ostern<\/option><option value=\"ostersonntag\" >Ostersonntag<\/option><option value=\"palmsonntag\" >Palmsonntag<\/option><option value=\"prophetie\" >Prophetie<\/option><option value=\"reife\" >Reife<\/option><option value=\"saat-und-ernte\" >Saat und Ernte<\/option><option value=\"safe-place\" >safe place<\/option><option value=\"schalom\" >Schalom<\/option><option value=\"schutz\" >Schutz<\/option><option value=\"segen\" >Segen<\/option><option value=\"sendschreiben-an-ephesus\" >Sendschreiben an Ephesus<\/option><option value=\"sendschreiben-an-thyatira\" >Sendschreiben an Thyatira<\/option><option value=\"sicherer-ort\" >sicherer Ort<\/option><option value=\"sieg\" >Sieg<\/option><option value=\"sinn\" >Sinn<\/option><option value=\"sinn-des-lebens\" >Sinn des Lebens<\/option><option value=\"sinn-im-leiden\" >Sinn im Leiden<\/option><option value=\"stephan-oester\" >Stephan Oester<\/option><option value=\"stiftshuette\" >Stiftsh\u00fctte<\/option><option value=\"taufe\" >Taufe<\/option><option value=\"umkehr\" >Umkehr<\/option><option value=\"unterscheiden\" >Unterscheiden<\/option><option value=\"vergangenheit\" >Vergangenheit<\/option><option value=\"vergebung\" >Vergebung<\/option><option value=\"verlorener-sohn\" >Verlorener Sohn<\/option><option value=\"vertrauen\" >Vertrauen<\/option><option value=\"vision\" >Vision<\/option><option value=\"vision-viva-kirche-liestal\" >Vision Viva Kirche Liestal<\/option><option value=\"wahrheit\" >Wahrheit<\/option><option value=\"warum-frage\" >Warum-Frage<\/option><option value=\"weihnachten\" >Weihnachten<\/option><option value=\"wiedergefundener-sohn\" >wiedergefundener Sohn<\/option><option value=\"wiederkunft\" >Wiederkunft<\/option><option value=\"wohlstands-schaedigung\" >Wohlstands-Sch\u00e4digung<\/option><option value=\"zeit-ereignisse\" >Zeit-Ereignisse<\/option><option value=\"zugang-zu-gott\" >Zugang zu Gott<\/option><option value=\"zum-fest-eingeladen\" >Zum Fest eingeladen!<\/option><option value=\"zweifel\" >Zweifel<\/option>\t\t\t\t\t<\/select>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<noscript>\n\t\t\t\t\t\t<div><input type=\"submit\" value=\"Submit\"\/><\/div>\n\t\t\t\t\t<\/noscript>\n\t\t\t\t<\/form>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t","sermons_blog_filters_series":"\t\t\t\t<div class=\"sm-filtering\">\n\t\t\t\t\t<div id=\"wpfc_sermon_sorting\" class=\"no-spacing\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"sortSeries\" style=\"display: inline-block\">\n\t\t\t\t<form action=\"https:\/\/www.vivakirche-liestal.ch\/en\/wp-json\/wp\/v2\/wpfc_sermon\/4009\/\" method=\"get\">\n\t\t\t\t\t<select name=\"wpfc_sermon_series\"\n\t\t\t\t\t\t\ttitle=\"Series\"\n\t\t\t\t\t\t\tid=\"wpfc_sermon_series\"\n\t\t\t\t\t\t\tonchange=\"if(this.options[this.selectedIndex].value !== ''){return this.form.submit()}else{window.location = window.location.href.split('?')[0];}\"\n\t\t\t\t\t\t\tautocomplete=\"off\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t<option value=\"\">Series<\/option>\n\t\t\t\t\t\t<option value=\"1-petrus\" >1. Petrus<\/option><option value=\"advent\" >Advent<\/option><option value=\"auf-jesus-ausgerichtet\" >Auf Jesus ausgerichtet<\/option><option value=\"auferstehung-jesu-christi\" >Auferstehung Jesu Christi<\/option><option value=\"begegnung-mit-gott\" >Begegnung mit Gott<\/option><option value=\"die-schoenheit-des-evangeliums\" >Die Sch\u00f6nheit des Evangeliums<\/option><option value=\"dienen\" >Dienen<\/option><option value=\"dienst\" >Dienst<\/option><option value=\"ehrlichkeit\" >Ehrlichkeit<\/option><option value=\"ein-leben-mit-gott\" >Ein Leben mit Gott<\/option><option value=\"esoterik\" >Esoterik<\/option><option value=\"feste-feiern\" >Feste feiern<\/option><option value=\"freude\" >Freude<\/option><option value=\"gebet\" >Gebet<\/option><option value=\"gebetswoche\" >Gebetswoche<\/option><option value=\"geschenk-gottes\" >Geschenk Gottes<\/option><option value=\"glaube\" >Glaube<\/option><option value=\"glaube-auf-dem-pruefstand\" >Glaube auf dem Pr\u00fcfstand<\/option><option value=\"gleichnisse\" >Gleichnisse<\/option><option value=\"gleichnisse-von-jesus-christus\" >Gleichnisse von Jesus Christus<\/option><option value=\"gottes-angesicht-suchen\" >Gottes Angesicht suchen<\/option><option value=\"gottes-heilige-gegenwart\" >Gottes heilige Gegenwart<\/option><option value=\"heilig\" >Heilig<\/option><option value=\"heiliger-geist\" >Heiliger Geist<\/option><option value=\"heiligkeit\" >Heiligkeit<\/option><option value=\"herausgefordert\" >herausgefordert<\/option><option value=\"hochsensibilitaet\" >Hochsensibilit\u00e4t<\/option><option value=\"hoffnung-in-stuermischen-zeiten\" >Hoffnung in st\u00fcrmischen Zeiten<\/option><option value=\"in-gottes-gegenwart-kommen\" >In Gottes Gegenwart kommen<\/option><option value=\"jahreslosung\" >Jahreslosung<\/option><option value=\"jesus-christus\" >Jesus Christus<\/option><option value=\"korrektur-bereitschaft\" >Korrektur-Bereitschaft<\/option><option value=\"leben\" >Leben<\/option><option value=\"lehre\" >Lehre<\/option><option value=\"life-2024\" >LIFE 2024<\/option><option value=\"live\" >Live<\/option><option value=\"live-2024\" >LIVE 2024<\/option><option value=\"loslassen-und-versoehnen\" >Loslassen und Vers\u00f6hnen<\/option><option value=\"love-your-neighbour\" >Love Your Neighbour<\/option><option value=\"muttertag\" >Muttertag<\/option><option value=\"nachfolge\" >Nachfolge<\/option><option value=\"neu\" >Neu<\/option><option value=\"neuro-diversitaet\" >Neuro-Diversit\u00e4t<\/option><option value=\"offenbarung\" >Offenbarung<\/option><option value=\"passion-jesu-christi\" >Passion Jesu Christi<\/option><option value=\"passions-woche\" >Passions-Woche<\/option><option value=\"passionswoche\" >Passionswoche<\/option><option value=\"psalmen\" >Psalmen<\/option><option value=\"segen\" >Segen<\/option><option value=\"segnung\" >Segnung<\/option><option value=\"sommer-gottesdienste\" >Sommer-Gottesdienste<\/option><option value=\"taufe\" >Taufe<\/option><option value=\"themen-des-life-seminars\" >Themen des LiFe-Seminars<\/option><option value=\"trio-predigtserie-herbst-2023\" >Trio-Predigtserie Herbst 2023<\/option><option value=\"trio-reihe\" >Trio-Reihe<\/option><option value=\"ueberfliessend-fruchtbar\" >\u00dcberfliessend fruchtbar<\/option><option value=\"vision-viva-kirche-liestal\" >Vision Viva Kirche Liestal<\/option><option value=\"viva-kirchen\" >Viva Kirchen<\/option><option value=\"vorbereitung-der-gebetswoche\" >Vorbereitung der Gebetswoche<\/option><option value=\"wer-uns-hoffen-laesst-1-petrus\" >Wer uns hoffen l\u00e4sst \/ 1. Petrus<\/option><option value=\"wir-leben-kirche\" >Wir leben KIrche<\/option><option value=\"zwischen-himmel-und-erde\" >Zwischen Himmel und Erde<\/option>\t\t\t\t\t<\/select>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<noscript>\n\t\t\t\t\t\t<div><input type=\"submit\" value=\"Submit\"\/><\/div>\n\t\t\t\t\t<\/noscript>\n\t\t\t\t<\/form>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t","sermons_blog_filters_preachers":"\t\t\t\t<div class=\"sm-filtering\">\n\t\t\t\t\t<div id=\"wpfc_sermon_sorting\" class=\"no-spacing\">\n\t\t\t\n\t\t\t\t\t<div class=\"sortPreacher\" style=\"display: inline-block\">\n\t\t\t\t<form action=\"https:\/\/www.vivakirche-liestal.ch\/en\/wp-json\/wp\/v2\/wpfc_sermon\/4009\/\" method=\"get\">\n\t\t\t\t\t<select name=\"wpfc_preacher\"\n\t\t\t\t\t\t\ttitle=\"Redner\"\n\t\t\t\t\t\t\tid=\"wpfc_preacher\"\n\t\t\t\t\t\t\tonchange=\"if(this.options[this.selectedIndex].value !== ''){return this.form.submit()}else{window.location = window.location.href.split('?')[0];}\"\n\t\t\t\t\t\t\tautocomplete=\"off\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t<option value=\"\">Redner<\/option>\n\t\t\t\t\t\t<option value=\"andy-thommen\" >Andy Thommen<\/option><option value=\"beni-sutter\" >Beni Sutter<\/option><option value=\"christian-seitz\" >Christian Seitz<\/option><option value=\"claudia-gloor\" >Claudia Gloor<\/option><option value=\"clemens-mager\" >Clemens Mager<\/option><option value=\"daniel-gloor\" >Daniel Gloor<\/option><option value=\"daniel-hofer\" >Daniel Hofer<\/option><option value=\"debora-sommer\" >Debora Sommer<\/option><option value=\"ferdinand-pankratz\" >Ferdinand Pankratz<\/option><option value=\"fraenzi-kort\" >Fr\u00e4nzi Kort<\/option><option value=\"fritz-stalder\" >Fritz Stalder<\/option><option value=\"heinz-thaler\" >Heinz Thaler<\/option><option value=\"james-senior\" >James Senior<\/option><option value=\"jonathan-verwer\" >Jonathan Verwer<\/option><option value=\"lukas-waefler\" >Lukas W\u00e4fler<\/option><option value=\"marc-finkbeiner\" >Marc Finkbeiner<\/option><option value=\"markus-burkhart\" >Markus Burkhart<\/option><option value=\"markus-eichenberger\" >Markus Eichenberger<\/option><option value=\"max-muster\" >Max Muster<\/option><option value=\"michael-widmer\" >Michael Widmer<\/option><option value=\"mitarbeiter-von-open-doors\" >Mitarbeiter von Open Doors<\/option><option value=\"peter-gloor\" >Peter Gloor<\/option><option value=\"philipp-eschbach\" >Philipp Eschbach<\/option><option value=\"rene-winkler\" >Ren\u00e9 Winkler<\/option><option value=\"stabler-und-eschbach\" >Stabler und Eschbach<\/option><option value=\"stefan-fuchser\" >Stefan Fuchser<\/option><option value=\"stefan-weber\" >Stefan Weber<\/option><option value=\"stephan-leuenberger\" >Stephan Leuenberger<\/option><option value=\"susanne-keller\" >Susanne Keller<\/option><option value=\"timon-forster\" >Timon Forster<\/option><option value=\"willy-burn\" >Willy Burn<\/option><option value=\"zoe-bee\" >Zo\u00eb Bee<\/option>\t\t\t\t\t<\/select>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<noscript>\n\t\t\t\t\t\t<div><input type=\"submit\" value=\"Submit\"\/><\/div>\n\t\t\t\t\t<\/noscript>\n\t\t\t\t<\/form>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t","sermons_blog_filters_books":"\t\t\t\t<div class=\"sm-filtering\">\n\t\t\t\t\t<div id=\"wpfc_sermon_sorting\" class=\"no-spacing\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"sortBooks\" style=\"display: inline-block\">\n\t\t\t\t<form action=\"https:\/\/www.vivakirche-liestal.ch\/en\/wp-json\/wp\/v2\/wpfc_sermon\/4009\/\" method=\"get\">\n\t\t\t\t\t<select name=\"wpfc_bible_book\"\n\t\t\t\t\t\t\ttitle=\"Book\"\n\t\t\t\t\t\t\tid=\"wpfc_bible_book\"\n\t\t\t\t\t\t\tonchange=\"if(this.options[this.selectedIndex].value !== ''){return this.form.submit()}else{window.location = window.location.href.split('?')[0];}\"\n\t\t\t\t\t\t\tautocomplete=\"off\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t<option value=\"\">Book<\/option>\n\t\t\t\t\t\t<option value=\"psalmen\" >Psalmen<\/option><option value=\"offenbarung\" >Offenbarung<\/option><option value=\"1-timotheus\" >1. Timotheus<\/option>\t\t\t\t\t<\/select>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<noscript>\n\t\t\t\t\t\t<div><input type=\"submit\" value=\"Submit\"\/><\/div>\n\t\t\t\t\t<\/noscript>\n\t\t\t\t<\/form>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t","sermons_blog_filters_service_types":"\t\t\t\t<div class=\"sm-filtering\">\n\t\t\t\t\t<div id=\"wpfc_sermon_sorting\" class=\"no-spacing\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"sortServiceTypes\" style=\"display: inline-block\">\n\t\t\t\t<form action=\"https:\/\/www.vivakirche-liestal.ch\/en\/wp-json\/wp\/v2\/wpfc_sermon\/4009\/\" method=\"get\">\n\t\t\t\t\t<select name=\"wpfc_service_type\"\n\t\t\t\t\t\t\ttitle=\"Dienstart\"\n\t\t\t\t\t\t\tid=\"wpfc_service_type\"\n\t\t\t\t\t\t\tonchange=\"if(this.options[this.selectedIndex].value !== ''){return this.form.submit()}else{window.location = window.location.href.split('?')[0];}\"\n\t\t\t\t\t\t\tautocomplete=\"off\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t<option value=\"\">Dienstart<\/option>\n\t\t\t\t\t\t<option value=\"gottesdienst\" >Gottesdienst<\/option><option value=\"tauf-gottesdienst\" >Tauf-Gottesdienst<\/option>\t\t\t\t\t<\/select>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<noscript>\n\t\t\t\t\t\t<div><input type=\"submit\" value=\"Submit\"\/><\/div>\n\t\t\t\t\t<\/noscript>\n\t\t\t\t<\/form>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t","sermons_blog_filters_dates":"\t\t\t\t<div class=\"sm-filtering\">\n\t\t\t\t\t<div id=\"wpfc_sermon_sorting\" class=\"no-spacing\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"sortDates\" style=\"display: inline-block\">\n\t\t\t\t<form action=\"https:\/\/www.vivakirche-liestal.ch\/en\/wp-json\/wp\/v2\/wpfc_sermon\/4009\/\" method=\"get\">\n\t\t\t\t\t<select name=\"wpfc_dates\"\n\t\t\t\t\t\t\ttitle=\"Date\"\n\t\t\t\t\t\t\tid=\"wpfc_dates\"\n\t\t\t\t\t\t\tonchange=\"if(this.options[this.selectedIndex].value !== ''){return this.form.submit()}else{window.location = window.location.href.split('?')[0];}\"\n\t\t\t\t\t\t\tautocomplete=\"off\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t<option value=\"\">Date<\/option>\n\t\t\t\t\t\t<option value=\"05-2026\" >May 2026<\/option><option value=\"04-2026\" >Apr 2026<\/option><option value=\"03-2026\" >Mar 2026<\/option><option value=\"02-2026\" >Feb 2026<\/option><option value=\"01-2026\" >Jan 2026<\/option><option value=\"12-2025\" >Dec 2025<\/option><option value=\"11-2025\" >Nov 2025<\/option><option value=\"10-2025\" >Oct 2025<\/option><option value=\"09-2025\" >Sep 2025<\/option><option value=\"08-2025\" >Aug 2025<\/option><option value=\"07-2025\" >Jul 2025<\/option><option value=\"06-2025\" >Jun 2025<\/option><option value=\"05-2025\" >May 2025<\/option><option value=\"04-2025\" >Apr 2025<\/option><option value=\"03-2025\" >Mar 2025<\/option><option value=\"02-2025\" >Feb 2025<\/option><option value=\"01-2025\" >Jan 2025<\/option><option value=\"12-2024\" >Dec 2024<\/option><option value=\"11-2024\" >Nov 2024<\/option><option value=\"10-2024\" >Oct 2024<\/option><option value=\"09-2024\" >Sep 2024<\/option><option value=\"08-2024\" >Aug 2024<\/option><option value=\"07-2024\" >Jul 2024<\/option><option value=\"06-2024\" >Jun 2024<\/option><option value=\"05-2024\" >May 2024<\/option><option value=\"04-2024\" >Apr 2024<\/option><option value=\"03-2024\" >Mar 2024<\/option><option value=\"02-2024\" >Feb 2024<\/option><option value=\"01-2024\" >Jan 2024<\/option><option value=\"12-2023\" >Dec 2023<\/option><option value=\"11-2023\" >Nov 2023<\/option><option value=\"10-2023\" >Oct 2023<\/option><option value=\"09-2023\" >Sep 2023<\/option><option value=\"08-2023\" >Aug 2023<\/option><option value=\"07-2023\" >Jul 2023<\/option><option value=\"06-2023\" >Jun 2023<\/option><option value=\"05-2023\" >May 2023<\/option><option value=\"04-2023\" >Apr 2023<\/option><option value=\"03-2023\" >Mar 2023<\/option><option value=\"02-2023\" >Feb 2023<\/option><option value=\"01-2023\" >Jan 2023<\/option><option value=\"12-2022\" >Dec 2022<\/option><option value=\"11-2022\" >Nov 2022<\/option><option value=\"10-2022\" >Oct 2022<\/option><option value=\"09-2022\" >Sep 2022<\/option><option value=\"08-2022\" >Aug 2022<\/option><option value=\"07-2022\" >Jul 2022<\/option><option value=\"06-2022\" >Jun 2022<\/option><option value=\"05-2022\" >May 2022<\/option><option value=\"04-2022\" >Apr 2022<\/option><option value=\"02-2022\" >Feb 2022<\/option><option value=\"01-2022\" >Jan 2022<\/option><option value=\"04-2021\" >Apr 2021<\/option>\t\t\t\t\t<\/select>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<noscript>\n\t\t\t\t\t\t<div><input type=\"submit\" value=\"Submit\"\/><\/div>\n\t\t\t\t\t<\/noscript>\n\t\t\t\t<\/form>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t","sermons_blog_image_url":"https:\/\/www.vivakirche-liestal.ch\/wp-content\/uploads\/2024\/11\/Trio-2025-Titel-1500.jpg","sermons_blog_video":"","sermons_blog_series":"<a href=\"https:\/\/www.vivakirche-liestal.ch\/en\/series\/glaube-auf-dem-pruefstand\/\" rel=\"tag\">Glaube auf dem Pr\u00fcfstand<\/a>","sermons_blog_meta_sermon_description":"","sermons_blog_show_readmore":false,"sermons_blog_audio":"<audio controls preload=\"metadata\" class=\"wpfc-sermon-player \" ><source src=\"https:\/\/www.vivakirche-liestal.ch\/wp-content\/uploads\/sermons\/2024\/11\/Vom-Zweifel-zum-Glauben_MB_3.11.24.mp3\" type=\"audio\/mp3\"><\/audio>","sermons_blog_preacher_image":"","sermons_blog_preacher":"<a href=\"https:\/\/www.vivakirche-liestal.ch\/en\/redner\/markus-burkhart\/\" rel=\"tag\">Markus Burkhart<\/a>","sermons_blog_bible_passage":"Johannes 20,24-29","sermons_blog_service_type":"<a href=\"https:\/\/www.vivakirche-liestal.ch\/en\/dienstart\/gottesdienst\/\" rel=\"tag\">Gottesdienst<\/a>","sermon_audio":"https:\/\/www.vivakirche-liestal.ch\/wp-content\/uploads\/sermons\/2024\/11\/Vom-Zweifel-zum-Glauben_MB_3.11.24.mp3","sermon_audio_duration":"00:29:18","_views":"41","bible_passage":"Johannes 20,24-29","sermon_video_embed":"","sermon_video_url":"","sermon_bulletin":"","_featured_url":"https:\/\/www.vivakirche-liestal.ch\/wp-content\/uploads\/2024\/11\/Trio-2025-Titel-1500.jpg","sermon_date":1730640120,"_sermon_date_auto":false,"_links":{"self":[{"href":"https:\/\/www.vivakirche-liestal.ch\/en\/wp-json\/wp\/v2\/wpfc_sermon\/4009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vivakirche-liestal.ch\/en\/wp-json\/wp\/v2\/wpfc_sermon"}],"about":[{"href":"https:\/\/www.vivakirche-liestal.ch\/en\/wp-json\/wp\/v2\/types\/wpfc_sermon"}],"author":[{"embeddable":true,"href":"https:\/\/www.vivakirche-liestal.ch\/en\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vivakirche-liestal.ch\/en\/wp-json\/wp\/v2\/comments?post=4009"}],"version-history":[{"count":1,"href":"https:\/\/www.vivakirche-liestal.ch\/en\/wp-json\/wp\/v2\/wpfc_sermon\/4009\/revisions"}],"predecessor-version":[{"id":4011,"href":"https:\/\/www.vivakirche-liestal.ch\/en\/wp-json\/wp\/v2\/wpfc_sermon\/4009\/revisions\/4011"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vivakirche-liestal.ch\/en\/wp-json\/wp\/v2\/media\/4006"}],"wp:attachment":[{"href":"https:\/\/www.vivakirche-liestal.ch\/en\/wp-json\/wp\/v2\/media?parent=4009"}],"wp:term":[{"taxonomy":"wpfc_preacher","embeddable":true,"href":"https:\/\/www.vivakirche-liestal.ch\/en\/wp-json\/wp\/v2\/wpfc_preacher?post=4009"},{"taxonomy":"wpfc_sermon_series","embeddable":true,"href":"https:\/\/www.vivakirche-liestal.ch\/en\/wp-json\/wp\/v2\/wpfc_sermon_series?post=4009"},{"taxonomy":"wpfc_sermon_topics","embeddable":true,"href":"https:\/\/www.vivakirche-liestal.ch\/en\/wp-json\/wp\/v2\/wpfc_sermon_topics?post=4009"},{"taxonomy":"wpfc_bible_book","embeddable":true,"href":"https:\/\/www.vivakirche-liestal.ch\/en\/wp-json\/wp\/v2\/wpfc_bible_book?post=4009"},{"taxonomy":"wpfc_service_type","embeddable":true,"href":"https:\/\/www.vivakirche-liestal.ch\/en\/wp-json\/wp\/v2\/wpfc_service_type?post=4009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}